{"id":89,"date":"2015-11-26T09:10:01","date_gmt":"2015-11-26T08:10:01","guid":{"rendered":"http:\/\/abacell.org\/actualidad\/?p=89"},"modified":"2016-07-11T16:26:50","modified_gmt":"2016-07-11T15:26:50","slug":"cinco-bebes-salvadores-han-nacido-en-espana-desde-que-se-autorizo-la-terapia-del-hermano-compatible","status":"publish","type":"post","link":"https:\/\/abacell.org\/actualidad\/2015\/11\/26\/cinco-bebes-salvadores-han-nacido-en-espana-desde-que-se-autorizo-la-terapia-del-hermano-compatible\/","title":{"rendered":"Cinco \u201cbeb\u00e9s salvadores\u201d han nacido en Espa\u00f1a desde que se autoriz\u00f3 la terapia del hermano compatible"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"563\" height=\"317\" src=\"https:\/\/www.youtube.com\/embed\/iUPGY3-QKqo?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>S\u00f3lo cinco \u201cbeb\u00e9s salvadores\u201d han nacido en Espa\u00f1a desde que en 2006 se autoriz\u00f3 el primer nacimiento programado para salvar a un hermano gravemente enfermo mediante el trasplante de c\u00e9lulas madre compatibles procedentes del cord\u00f3n umbilical, seg\u00fan desvela un reciente <a href=\"http:\/\/www.elmundo.es\/salud\/2015\/11\/02\/56177e4fe2704e49538b4628.html\" target=\"_blank\">reportaje del diario El Mundo<\/a>.<\/p>\n<p>El primer caso se remonta a 2008 con el nacimiento de Javier, un beb\u00e9 nacido en Algeciras para curar a su hermano Andr\u00e9s de beta talasemia, una anemia cong\u00e9nita que se le manifest\u00f3 a los cuatro meses de edad. Desde entonces, han nacido dos gemelos en Barcelona para curar a un hermano mayor de adrenoleucodistrofia, otro en Sevilla para el tratamiento de una aplasia medular y un quinto en Madrid para una anemia de Fanconi.<\/p>\n<p>El Presidente de la ONT (Organizaci\u00f3n Nacional de Trasplantes), Rafael Matesanz, ha informado que desde 2006 las autoridades sanitarias han recibido 66 solicitudes de familias para concebir un hijo gen\u00e9ticamente compatible con otro enfermo. De ellas, se han autorizado 45 casos (el 68%), pero pocos han conseguido su objetivo. Aunque no existe un registro oficial y sistem\u00e1tico de \u201chermanos salvadores\u201d, se sabe que muchos intentos se frustran por muy diversas razones.<\/p>\n<p>La primera de ellas es gen\u00e9tica. Las posibilidades de obtener un embri\u00f3n sano (sin los defectos gen\u00e9ticos del padre o la madre) son tres de cada cuatro, pero que adem\u00e1s sea gen\u00e9ticamente compatible con el hermano es s\u00f3lo del 25%. La segunda gran limitaci\u00f3n es t\u00e9cnica, ya que el 75% de los embriones sanos y compatibles no se desarrolla adecuadamente <em>in vitro<\/em>, lo que reduce las posibilidades finales a un 5% de \u00e9xitos.<\/p>\n<p>Por ello, desde la ONT el doctor Matesanz recomienda que, antes de iniciar un proceso de estas caracter\u00edsticas, conviene buscar c\u00e9lulas madre de un donante compatible a trav\u00e9s de la Red Espa\u00f1ola de Donantes de M\u00e9dula \u00d3sea (REDMO), gestionada por la Fundaci\u00f3n Jos\u00e9 Carreras y que, adem\u00e1s, incluye la red p\u00fablica de unidades de sangre de cord\u00f3n umbilical.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3lo cinco \u201cbeb\u00e9s salvadores\u201d han nacido en Espa\u00f1a desde que en 2006 se autoriz\u00f3 el primer nacimiento programado para salvar a un hermano gravemente enfermo mediante el trasplante de c\u00e9lulas madre compatibles procedentes del cord\u00f3n umbilical, seg\u00fan desvela un reciente reportaje del diario El Mundo. El primer caso se remonta a 2008 con el nacimiento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,204],"tags":[11,13,12,9,8,18,19,14,17,16,15,7,10],"class_list":["post-89","post","type-post","status-publish","format-standard","hentry","category-historias-reales","category-made-in-spain","tag-adrenoleucodistrofia","tag-anemia-de-fanconi","tag-aplasia-medular","tag-bebe-medicamento","tag-bebes-salvadores","tag-fundacion-jose-carreras","tag-medula-osea","tag-ont","tag-rafael-matesanz","tag-red-espanola-de-donantes-de-medula-osea","tag-redmo","tag-scu","tag-talasemia"],"_links":{"self":[{"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":6,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":92,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/posts\/89\/revisions\/92"}],"wp:attachment":[{"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abacell.org\/actualidad\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}